{"id":4043,"date":"2026-05-07T07:04:16","date_gmt":"2026-05-07T07:04:16","guid":{"rendered":"https:\/\/museosdealicante.com\/?post_type=portfolio&#038;p=4043"},"modified":"2026-05-07T07:42:27","modified_gmt":"2026-05-07T07:42:27","slug":"lonja-del-pescado-dim26","status":"publish","type":"portfolio","link":"https:\/\/museosdealicante.com\/va\/portfolio-item\/lonja-del-pescado-dim26\/","title":{"rendered":"LONJA DEL PESCADO DIM26"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":303,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"portfolio-types":[34],"class_list":["post-4043","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-dim-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LONJA DEL PESCADO DIM26 - MUSEA | Museos de Alicante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museosdealicante.com\/va\/portfolio-item\/lonja-del-pescado-dim26\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LONJA DEL PESCADO DIM26 - MUSEA | Museos de Alicante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museosdealicante.com\/va\/portfolio-item\/lonja-del-pescado-dim26\/\" \/>\n<meta property=\"og:site_name\" content=\"MUSEA | Museos de Alicante\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T07:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museosdealicante.com\/wp-content\/uploads\/2022\/05\/lonja.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/\",\"url\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/\",\"name\":\"LONJA DEL PESCADO DIM26 - MUSEA | Museos de Alicante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museosdealicante.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/lonja.png\",\"datePublished\":\"2026-05-07T07:04:16+00:00\",\"dateModified\":\"2026-05-07T07:42:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museosdealicante.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/lonja.png\",\"contentUrl\":\"https:\\\/\\\/museosdealicante.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/lonja.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/portfolio-item\\\/lonja-del-pescado-dim26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/museosdealicante.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LONJA DEL PESCADO DIM26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museosdealicante.com\\\/#website\",\"url\":\"https:\\\/\\\/museosdealicante.com\\\/\",\"name\":\"MUSEA | Museos de Alicante\",\"description\":\"Toda la oferta sobre arte, cultura y patrimonio de la ciudad, toda la actualidad de los museos de Alicante\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museosdealicante.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LONJA DEL PESCADO DIM26 - MUSEA | Museos de Alicante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museosdealicante.com\/va\/portfolio-item\/lonja-del-pescado-dim26\/","og_locale":"ca_ES","og_type":"article","og_title":"LONJA DEL PESCADO DIM26 - MUSEA | Museos de Alicante","og_url":"https:\/\/museosdealicante.com\/va\/portfolio-item\/lonja-del-pescado-dim26\/","og_site_name":"MUSEA | Museos de Alicante","article_modified_time":"2026-05-07T07:42:27+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/museosdealicante.com\/wp-content\/uploads\/2022\/05\/lonja.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/","url":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/","name":"LONJA DEL PESCADO DIM26 - MUSEA | Museos de Alicante","isPartOf":{"@id":"https:\/\/museosdealicante.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/#primaryimage"},"image":{"@id":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/#primaryimage"},"thumbnailUrl":"https:\/\/museosdealicante.com\/wp-content\/uploads\/2022\/05\/lonja.png","datePublished":"2026-05-07T07:04:16+00:00","dateModified":"2026-05-07T07:42:27+00:00","breadcrumb":{"@id":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/#primaryimage","url":"https:\/\/museosdealicante.com\/wp-content\/uploads\/2022\/05\/lonja.png","contentUrl":"https:\/\/museosdealicante.com\/wp-content\/uploads\/2022\/05\/lonja.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/museosdealicante.com\/portfolio-item\/lonja-del-pescado-dim26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/museosdealicante.com\/"},{"@type":"ListItem","position":2,"name":"LONJA DEL PESCADO DIM26"}]},{"@type":"WebSite","@id":"https:\/\/museosdealicante.com\/#website","url":"https:\/\/museosdealicante.com\/","name":"MUSEA | Museos de Alicante","description":"Toda la oferta sobre arte, cultura y patrimonio de la ciudad, toda la actualidad de los museos de Alicante","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museosdealicante.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/portfolio\/4043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/comments?post=4043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/media\/303"}],"wp:attachment":[{"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/media?parent=4043"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/museosdealicante.com\/va\/wp-json\/wp\/v2\/portfolio-types?post=4043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}